{"id":2435,"date":"2014-09-23T17:39:24","date_gmt":"2014-09-23T15:39:24","guid":{"rendered":"https:\/\/bodeweb.de\/blog\/?p=2435"},"modified":"2022-02-03T09:26:05","modified_gmt":"2022-02-03T08:26:05","slug":"triton-bucht-der-film-ist-endlich-online","status":"publish","type":"post","link":"https:\/\/bodeweb.de\/blog\/triton-bucht-der-film-ist-endlich-online\/","title":{"rendered":"Triton Bucht &#8211; Der Film ist endlich online!"},"content":{"rendered":"\n<p><em>23. September 2014<\/em><\/p>\n\n\n<p>Nach insgesamt drei Besuchen der <a href=\"https:\/\/bodeweb.de\/west-papua\/triton_bucht_tauchen.htm\">Triton Bucht<\/a> ist mein Film \u00fcber diese paradiesische Bucht im S\u00fcden der Vogelkopf Halbinsel, im indonesischen Teil von Neuguinea endlich fertig.<\/p>\n<p>Meine erste Expedition liegt schon einige Jahre zur\u00fcck. 2007 war ich mit Graham Abbott und der Seahorse das erst mal dort. Ein Jahr zuvor hatte Graham als Cruise Manager die erste Expedition von Conservation International in die Triton Bucht gef\u00fchrt.<br \/>Bekanntlich kam die Expedition mit etlichen Neuentdeckungen zur\u00fcck, u. a. wurde damals der &#8216;Walking Shark&#8217; als neue Haiart in der Triton Bucht zum ersten Mal gesichtet.<br \/>2009 folgte dann der n\u00e4chste Besuch mit der Raja Ampat Explorer und in diesem April haben wir mit der Amira einen dritten Versuch gewagt.<\/p>\n<h2>Film \u00fcber die Triton Bucht<\/h2>\n<p>Der nun entstandene Film enth\u00e4lt Episoden aus allen drei Safaris.\u00a0Da ich seit zwei Jahren auch stolzer Besitzer eines dji Phantom Quadrokopters samt Gimbal und GoPro Hero 3 BE Kamera bin, konnte ich bei unserem letzten Besuch einige Luftaufnahmen der Bucht machen, die nun die Triton Bucht aus einer neuen Perspektive zeigen. Dadurch hat der Film meiner Meinung nach sehr gewonnen.<\/p>\n<p>[gallery ids=&#8221;2460,2461,2457,2458,2455&#8243;]<\/p>\n<h2>Nikolai Nikolajewitsch Miklucho-Maklai<\/h2>\n<p>Bei meinen Recherchen \u00fcber die Bucht bin ich auf Nikolai Nikolajewitsch Miklucho-Maklai gesto\u00dfen. Dieser russische Forscher und Abenteuer war im 19. Jahrhundert eine Ber\u00fchmtheit, weil er als erster Wei\u00dfer ein Jahr lang an der Nordk\u00fcste Neuguineas unter den &#8216;menschenfressenden&#8217; Eingeborenen gelebt &#8211; und \u00fcberlebt hatte!<\/p>\n<p>Nach seiner R\u00fcckkehr aus Neuguinea verbrachte er auch einige Zeit in Indonesien und unternahm 1874 von Ternate aus eine Expedition in die Triton Bucht. \u00dcber diese abenteuerliche Fahrt und den Aufenthalt in der Bucht berichtet er in seinem Tagebuch (Niklouho-Maclay, N., Travels to New Guinea, Moscow 1982).<\/p>\n<p>[gallery ids=&#8221;2440,2441&#8243;]<\/p>\n<p>Da er ziemlich genau den Ort beschrieben hat, wo er in der Triton Bucht gelebt hat, gingen wir auf die Suche, und ich bin mir ziemlich sichert, dass wir den Ort fanden, an dem seine H\u00fctte stand.<\/p>\n<p>Daraus lie\u00df sich nat\u00fcrlich eine interessante Story f\u00fcr den Film stricken&#8230;<\/p>\n<p>Die Triton Bucht ist \u00fcberhaupt reich an geschichtlichen Zeugnissen. Die Felsmalereien, die man hier findet, sind ziemlich einzigartig und stammen vermutlich aus einer Zeit, als vorbei ziehende J\u00e4ger und Sammler auf dem Weg nach Australien hier halt machten.<\/p>\n<p>[gallery ids=&#8221;2456,2454,2453,2452,2451,2450,2449,2448,2446&#8243;]<\/p>\n<p>Wir haben zwar bei unserem letzten Besuch nicht die hier fast station\u00e4ren Walhaie gesichtet, aber auch ohne sie ist die Unterwasserwelt der Bucht mit den riesigen Fischschw\u00e4rmen allemal ein Besuch wert. Ich kann daher auch nicht ausschlie\u00dfen, dass es sogar noch einen vierten Besuch der Bucht geben wird. Wer wei\u00df?<\/p>\n<p>\u00a0<\/p>\n<p><iframe loading=\"lazy\" title=\"Die Triton Bucht - Auf Entdeckungsfahrt amVogelkopf von Neuguinea\" src=\"https:\/\/player.vimeo.com\/video\/106488632?dnt=1&amp;app_id=122963\" width=\"500\" height=\"281\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write\"><\/iframe><\/p>\n<p><strong>Weitere Links:<\/strong><br \/>Englische Version des Films: <a href=\"http:\/\/www.vimeo.com\/bodeweb\/tritonbay\">http:\/\/www.vimeo.com\/bodeweb\/tritonbay<\/a><\/p>\n<p>Auf YouTube (mindestens in 720p abspielen!):<br \/>Englisch: <a href=\"http:\/\/youtu.be\/h794AyytU6k\">http:\/\/youtu.be\/h794AyytU6k<\/a><br \/>Deutsch: <a href=\"http:\/\/youtu.be\/e3QV3bXsjP4\">http:\/\/youtu.be\/e3QV3bXsjP4<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>23. September 2014 Nach insgesamt drei Besuchen der Triton Bucht ist mein Film \u00fcber diese paradiesische Bucht im S\u00fcden der Vogelkopf Halbinsel, im indonesischen Teil von Neuguinea endlich fertig. Meine&#8230;<span class=\"screen-reader-text\">  Triton Bucht &#8211; Der Film ist endlich online!<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[455,4],"tags":[16,25,100,138,163,164,225,239,240,279,280,283,371,390,414,429],"class_list":["post-2435","post","type-post","status-publish","format-standard","hentry","category-tauchen","category-video","tag-amira","tag-artenvielfalt","tag-felsmalereien","tag-indonesien","tag-koon","tag-kopfjagd","tag-misool","tag-neuguinea","tag-nikolai-nikolajewitsch-miklucho-maklai","tag-quadkopter","tag-quadrokopter","tag-raja-ampat","tag-ternate","tag-triton-bucht","tag-vogelkopf","tag-walking-shark"],"geo":{"latitude":-3.8478124,"longitude":134.0881348,"description":"Unnamed Road, Kamaka, Kec. Kaimana, Kabupaten Kaimana, Papua Bar., Indonesien"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Triton Bucht - Der Film ist endlich online! - BodeBlog-Tauchen in Indonesien<\/title>\n<meta name=\"description\" content=\"Der Film \u00fcber die Triton Bucht ist fertig. Im April 2014 habe ich die Bucht zum dritten Mal besucht, um Spuren des russischen Forschers und Entdeckers Nikolai Nikolajewitsch Miklucho-Maklai zu finden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bodeweb.de\/blog\/triton-bucht-der-film-ist-endlich-online\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Triton Bucht - Der Film ist endlich online! - BodeBlog-Tauchen in Indonesien\" \/>\n<meta property=\"og:description\" content=\"Der Film \u00fcber die Triton Bucht ist fertig. Im April 2014 habe ich die Bucht zum dritten Mal besucht, um Spuren des russischen Forschers und Entdeckers Nikolai Nikolajewitsch Miklucho-Maklai zu finden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bodeweb.de\/blog\/triton-bucht-der-film-ist-endlich-online\/\" \/>\n<meta property=\"og:site_name\" content=\"BodeBlog-Tauchen in Indonesien\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-23T15:39:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-03T08:26:05+00:00\" \/>\n<meta name=\"author\" content=\"Michael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/triton-bucht-der-film-ist-endlich-online\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/triton-bucht-der-film-ist-endlich-online\\\/\"},\"author\":{\"name\":\"Michael\",\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/#\\\/schema\\\/person\\\/de787d16d54da0697c0bf296fbf34d03\"},\"headline\":\"Triton Bucht &#8211; Der Film ist endlich online!\",\"datePublished\":\"2014-09-23T15:39:24+00:00\",\"dateModified\":\"2022-02-03T08:26:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/triton-bucht-der-film-ist-endlich-online\\\/\"},\"wordCount\":475,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/#\\\/schema\\\/person\\\/de787d16d54da0697c0bf296fbf34d03\"},\"keywords\":[\"Amira\",\"Artenvielfalt\",\"Felsmalereien\",\"Indonesien\",\"Koon\",\"Kopfjagd\",\"Misool\",\"Neuguinea\",\"Nikolai Nikolajewitsch Miklucho-Maklai\",\"Quadkopter\",\"Quadrokopter\",\"Raja Ampat\",\"Ternate\",\"Triton Bucht\",\"Vogelkopf\",\"Walking Shark\"],\"articleSection\":[\"Tauchen\",\"Video\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bodeweb.de\\\/blog\\\/triton-bucht-der-film-ist-endlich-online\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/triton-bucht-der-film-ist-endlich-online\\\/\",\"url\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/triton-bucht-der-film-ist-endlich-online\\\/\",\"name\":\"Triton Bucht - Der Film ist endlich online! - BodeBlog-Tauchen in Indonesien\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/#website\"},\"datePublished\":\"2014-09-23T15:39:24+00:00\",\"dateModified\":\"2022-02-03T08:26:05+00:00\",\"description\":\"Der Film \u00fcber die Triton Bucht ist fertig. Im April 2014 habe ich die Bucht zum dritten Mal besucht, um Spuren des russischen Forschers und Entdeckers Nikolai Nikolajewitsch Miklucho-Maklai zu finden.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/triton-bucht-der-film-ist-endlich-online\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bodeweb.de\\\/blog\\\/triton-bucht-der-film-ist-endlich-online\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/triton-bucht-der-film-ist-endlich-online\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Triton Bucht &#8211; Der Film ist endlich online!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/\",\"name\":\"BodeBlog-Tauchen in Indonesien\",\"description\":\"Informationen \u00fcber Tauchen in Indonesien\",\"publisher\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/#\\\/schema\\\/person\\\/de787d16d54da0697c0bf296fbf34d03\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/#\\\/schema\\\/person\\\/de787d16d54da0697c0bf296fbf34d03\",\"name\":\"Michael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g\",\"caption\":\"Michael\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Triton Bucht - Der Film ist endlich online! - BodeBlog-Tauchen in Indonesien","description":"Der Film \u00fcber die Triton Bucht ist fertig. Im April 2014 habe ich die Bucht zum dritten Mal besucht, um Spuren des russischen Forschers und Entdeckers Nikolai Nikolajewitsch Miklucho-Maklai zu finden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bodeweb.de\/blog\/triton-bucht-der-film-ist-endlich-online\/","og_locale":"de_DE","og_type":"article","og_title":"Triton Bucht - Der Film ist endlich online! - BodeBlog-Tauchen in Indonesien","og_description":"Der Film \u00fcber die Triton Bucht ist fertig. Im April 2014 habe ich die Bucht zum dritten Mal besucht, um Spuren des russischen Forschers und Entdeckers Nikolai Nikolajewitsch Miklucho-Maklai zu finden.","og_url":"https:\/\/bodeweb.de\/blog\/triton-bucht-der-film-ist-endlich-online\/","og_site_name":"BodeBlog-Tauchen in Indonesien","article_published_time":"2014-09-23T15:39:24+00:00","article_modified_time":"2022-02-03T08:26:05+00:00","author":"Michael","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Michael","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bodeweb.de\/blog\/triton-bucht-der-film-ist-endlich-online\/#article","isPartOf":{"@id":"https:\/\/bodeweb.de\/blog\/triton-bucht-der-film-ist-endlich-online\/"},"author":{"name":"Michael","@id":"https:\/\/bodeweb.de\/blog\/#\/schema\/person\/de787d16d54da0697c0bf296fbf34d03"},"headline":"Triton Bucht &#8211; Der Film ist endlich online!","datePublished":"2014-09-23T15:39:24+00:00","dateModified":"2022-02-03T08:26:05+00:00","mainEntityOfPage":{"@id":"https:\/\/bodeweb.de\/blog\/triton-bucht-der-film-ist-endlich-online\/"},"wordCount":475,"commentCount":0,"publisher":{"@id":"https:\/\/bodeweb.de\/blog\/#\/schema\/person\/de787d16d54da0697c0bf296fbf34d03"},"keywords":["Amira","Artenvielfalt","Felsmalereien","Indonesien","Koon","Kopfjagd","Misool","Neuguinea","Nikolai Nikolajewitsch Miklucho-Maklai","Quadkopter","Quadrokopter","Raja Ampat","Ternate","Triton Bucht","Vogelkopf","Walking Shark"],"articleSection":["Tauchen","Video"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bodeweb.de\/blog\/triton-bucht-der-film-ist-endlich-online\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bodeweb.de\/blog\/triton-bucht-der-film-ist-endlich-online\/","url":"https:\/\/bodeweb.de\/blog\/triton-bucht-der-film-ist-endlich-online\/","name":"Triton Bucht - Der Film ist endlich online! - BodeBlog-Tauchen in Indonesien","isPartOf":{"@id":"https:\/\/bodeweb.de\/blog\/#website"},"datePublished":"2014-09-23T15:39:24+00:00","dateModified":"2022-02-03T08:26:05+00:00","description":"Der Film \u00fcber die Triton Bucht ist fertig. Im April 2014 habe ich die Bucht zum dritten Mal besucht, um Spuren des russischen Forschers und Entdeckers Nikolai Nikolajewitsch Miklucho-Maklai zu finden.","breadcrumb":{"@id":"https:\/\/bodeweb.de\/blog\/triton-bucht-der-film-ist-endlich-online\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bodeweb.de\/blog\/triton-bucht-der-film-ist-endlich-online\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bodeweb.de\/blog\/triton-bucht-der-film-ist-endlich-online\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/bodeweb.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Triton Bucht &#8211; Der Film ist endlich online!"}]},{"@type":"WebSite","@id":"https:\/\/bodeweb.de\/blog\/#website","url":"https:\/\/bodeweb.de\/blog\/","name":"BodeBlog-Tauchen in Indonesien","description":"Informationen \u00fcber Tauchen in Indonesien","publisher":{"@id":"https:\/\/bodeweb.de\/blog\/#\/schema\/person\/de787d16d54da0697c0bf296fbf34d03"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bodeweb.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/bodeweb.de\/blog\/#\/schema\/person\/de787d16d54da0697c0bf296fbf34d03","name":"Michael","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g","caption":"Michael"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g"}}]}},"_links":{"self":[{"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/posts\/2435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/comments?post=2435"}],"version-history":[{"count":0,"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/posts\/2435\/revisions"}],"wp:attachment":[{"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/media?parent=2435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/categories?post=2435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/tags?post=2435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}