{"id":2672,"date":"2015-08-08T14:27:51","date_gmt":"2015-08-08T12:27:51","guid":{"rendered":"https:\/\/bodeweb.de\/blog\/?p=2672"},"modified":"2020-09-04T21:21:21","modified_gmt":"2020-09-04T19:21:21","slug":"siren-flotte-schiff-nr-5-geht-unter","status":"publish","type":"post","link":"https:\/\/bodeweb.de\/blog\/siren-flotte-schiff-nr-5-geht-unter\/","title":{"rendered":"Siren Flotte: Schiff Nr. 5 l\u00e4uft auf Riff"},"content":{"rendered":"\n<p><em>08. August 2015<\/em><\/p>\n\n\n<p>In der Nacht vom 3. auf den 4. August ist die Palau Siren vor Palau auf ein Riff gelaufen. Alle G\u00e4ste und Besatzungsmitglieder konnten gerettet werden.<\/p>\n<p><a href=\"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/08\/A1-Palau_652_389_90.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2676 size-medium\" src=\"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/08\/A1-Palau_652_389_90-300x179.jpg\" alt=\"Palau Siren\" width=\"300\" height=\"179\" srcset=\"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/08\/A1-Palau_652_389_90-300x179.jpg 300w, https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/08\/A1-Palau_652_389_90.jpg 652w, https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/08\/A1-Palau_652_389_90-300x179@2x.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Damit sind in den letzten sechs Jahren insgesamt f\u00fcnf Schiffe aus der Siren Flotte gesunken. Die letzten Ungl\u00fccke liegen noch gar nicht so lange zur\u00fcck. Genau so schnell wie <a href=\"http:\/\/sirenfleet.com\/liveaboards\/palau.html#g_vsig1_0\">WWDS<\/a> (World Wide Dive &amp; Sail) neue Tauchschiffe auf den Markt wirft, gehen diese auch wieder unter. Es gibt keinen Tauchschiffanbieter, der in den letzten Jahren so viele Schiffe verloren hat wie WWDS.<br \/>Nach dem Untergang der <a href=\"https:\/\/bodeweb.de\/blog\/ein-bisschen-notfall\/\">Oriental Siren<\/a> im Juni 2012 habe ich bereits die Frage aufgeworfen, ob diese Firma nicht ein gro\u00dfes Sicherheitsproblem hat. Wer als Reiseanbieter noch Schiffe aus der Siren Flotte im Angebot hat, sollte sich sehr gut \u00fcberlegen,\u00a0ob er diese Tauchschiffe weiter verkaufen will.<\/p>\n<p><strong>Update:<\/strong><\/p>\n<p>Mik Jennings, Sales und Marketing-Manager von WWDS, erwartet das die Palau Siren wieder flott gemacht werden kann. Das Schiff ist nicht total gesunken. Es hatte zwar Wasser aufgenommen, aber immerhin stellte sich nach einer Inspektion heraus, dass der Rumpf unbesch\u00e4digt geblieben ist und das Schiff repariert werden kann. Wann die Reparatur abgeschlossen sein wird, konnte Jennings noch nicht sagen. Er versichert aber, dass Sicherheit erste Priorit\u00e4t habe. G\u00e4ste w\u00fcrden erst wieder an Bord kommen, wenn die Palau Siren wieder voll funktionsf\u00e4hig sei.<\/p>","protected":false},"excerpt":{"rendered":"<p>08. August 2015 In der Nacht vom 3. auf den 4. August ist die Palau Siren vor Palau auf ein Riff gelaufen. Alle G\u00e4ste und Besatzungsmitglieder konnten gerettet werden. Damit&#8230;<span class=\"screen-reader-text\">  Siren Flotte: Schiff Nr. 5 l\u00e4uft auf Riff<\/span><\/p>\n","protected":false},"author":1,"featured_media":2676,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[455],"tags":[250,251,330,331,364,449],"class_list":["post-2672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tauchen","tag-palau","tag-palau-siren","tag-siren","tag-siren-flotte","tag-tauchschiff","tag-wwds"],"geo":{"latitude":7.5149798,"longitude":134.5825195,"description":"Palau"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Siren Flotte: Schiff Nr. 5 l\u00e4uft auf Riff - BodeBlog-Tauchen in Indonesien<\/title>\n<meta name=\"description\" content=\"Mit der Palau Siren versinkt innerhalb weniger Jahre das f\u00fcnfte Schiff aus der Siren Flotte.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bodeweb.de\/blog\/siren-flotte-schiff-nr-5-geht-unter\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Siren Flotte: Schiff Nr. 5 l\u00e4uft auf Riff - BodeBlog-Tauchen in Indonesien\" \/>\n<meta property=\"og:description\" content=\"Mit der Palau Siren versinkt innerhalb weniger Jahre das f\u00fcnfte Schiff aus der Siren Flotte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bodeweb.de\/blog\/siren-flotte-schiff-nr-5-geht-unter\/\" \/>\n<meta property=\"og:site_name\" content=\"BodeBlog-Tauchen in Indonesien\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-08T12:27:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-04T19:21:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/08\/A1-Palau_652_389_90.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"652\" \/>\n\t<meta property=\"og:image:height\" content=\"389\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/siren-flotte-schiff-nr-5-geht-unter\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/siren-flotte-schiff-nr-5-geht-unter\\\/\"},\"author\":{\"name\":\"Michael\",\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/#\\\/schema\\\/person\\\/de787d16d54da0697c0bf296fbf34d03\"},\"headline\":\"Siren Flotte: Schiff Nr. 5 l\u00e4uft auf Riff\",\"datePublished\":\"2015-08-08T12:27:51+00:00\",\"dateModified\":\"2020-09-04T19:21:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/siren-flotte-schiff-nr-5-geht-unter\\\/\"},\"wordCount\":234,\"commentCount\":10,\"publisher\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/#\\\/schema\\\/person\\\/de787d16d54da0697c0bf296fbf34d03\"},\"image\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/siren-flotte-schiff-nr-5-geht-unter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/A1-Palau_652_389_90.jpg\",\"keywords\":[\"Palau\",\"Palau Siren\",\"Siren\",\"Siren Flotte\",\"Tauchschiff\",\"WWDS\"],\"articleSection\":[\"Tauchen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bodeweb.de\\\/blog\\\/siren-flotte-schiff-nr-5-geht-unter\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/siren-flotte-schiff-nr-5-geht-unter\\\/\",\"url\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/siren-flotte-schiff-nr-5-geht-unter\\\/\",\"name\":\"Siren Flotte: Schiff Nr. 5 l\u00e4uft auf Riff - BodeBlog-Tauchen in Indonesien\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/siren-flotte-schiff-nr-5-geht-unter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/siren-flotte-schiff-nr-5-geht-unter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/A1-Palau_652_389_90.jpg\",\"datePublished\":\"2015-08-08T12:27:51+00:00\",\"dateModified\":\"2020-09-04T19:21:21+00:00\",\"description\":\"Mit der Palau Siren versinkt innerhalb weniger Jahre das f\u00fcnfte Schiff aus der Siren Flotte.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/siren-flotte-schiff-nr-5-geht-unter\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bodeweb.de\\\/blog\\\/siren-flotte-schiff-nr-5-geht-unter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/siren-flotte-schiff-nr-5-geht-unter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/A1-Palau_652_389_90.jpg\",\"contentUrl\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/A1-Palau_652_389_90.jpg\",\"width\":652,\"height\":389,\"caption\":\"Palau Siren\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/siren-flotte-schiff-nr-5-geht-unter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Siren Flotte: Schiff Nr. 5 l\u00e4uft auf Riff\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/\",\"name\":\"BodeBlog-Tauchen in Indonesien\",\"description\":\"Informationen \u00fcber Tauchen in Indonesien\",\"publisher\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/#\\\/schema\\\/person\\\/de787d16d54da0697c0bf296fbf34d03\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/#\\\/schema\\\/person\\\/de787d16d54da0697c0bf296fbf34d03\",\"name\":\"Michael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g\",\"caption\":\"Michael\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Siren Flotte: Schiff Nr. 5 l\u00e4uft auf Riff - BodeBlog-Tauchen in Indonesien","description":"Mit der Palau Siren versinkt innerhalb weniger Jahre das f\u00fcnfte Schiff aus der Siren Flotte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bodeweb.de\/blog\/siren-flotte-schiff-nr-5-geht-unter\/","og_locale":"de_DE","og_type":"article","og_title":"Siren Flotte: Schiff Nr. 5 l\u00e4uft auf Riff - BodeBlog-Tauchen in Indonesien","og_description":"Mit der Palau Siren versinkt innerhalb weniger Jahre das f\u00fcnfte Schiff aus der Siren Flotte.","og_url":"https:\/\/bodeweb.de\/blog\/siren-flotte-schiff-nr-5-geht-unter\/","og_site_name":"BodeBlog-Tauchen in Indonesien","article_published_time":"2015-08-08T12:27:51+00:00","article_modified_time":"2020-09-04T19:21:21+00:00","og_image":[{"width":652,"height":389,"url":"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/08\/A1-Palau_652_389_90.jpg","type":"image\/jpeg"}],"author":"Michael","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Michael","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bodeweb.de\/blog\/siren-flotte-schiff-nr-5-geht-unter\/#article","isPartOf":{"@id":"https:\/\/bodeweb.de\/blog\/siren-flotte-schiff-nr-5-geht-unter\/"},"author":{"name":"Michael","@id":"https:\/\/bodeweb.de\/blog\/#\/schema\/person\/de787d16d54da0697c0bf296fbf34d03"},"headline":"Siren Flotte: Schiff Nr. 5 l\u00e4uft auf Riff","datePublished":"2015-08-08T12:27:51+00:00","dateModified":"2020-09-04T19:21:21+00:00","mainEntityOfPage":{"@id":"https:\/\/bodeweb.de\/blog\/siren-flotte-schiff-nr-5-geht-unter\/"},"wordCount":234,"commentCount":10,"publisher":{"@id":"https:\/\/bodeweb.de\/blog\/#\/schema\/person\/de787d16d54da0697c0bf296fbf34d03"},"image":{"@id":"https:\/\/bodeweb.de\/blog\/siren-flotte-schiff-nr-5-geht-unter\/#primaryimage"},"thumbnailUrl":"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/08\/A1-Palau_652_389_90.jpg","keywords":["Palau","Palau Siren","Siren","Siren Flotte","Tauchschiff","WWDS"],"articleSection":["Tauchen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bodeweb.de\/blog\/siren-flotte-schiff-nr-5-geht-unter\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bodeweb.de\/blog\/siren-flotte-schiff-nr-5-geht-unter\/","url":"https:\/\/bodeweb.de\/blog\/siren-flotte-schiff-nr-5-geht-unter\/","name":"Siren Flotte: Schiff Nr. 5 l\u00e4uft auf Riff - BodeBlog-Tauchen in Indonesien","isPartOf":{"@id":"https:\/\/bodeweb.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bodeweb.de\/blog\/siren-flotte-schiff-nr-5-geht-unter\/#primaryimage"},"image":{"@id":"https:\/\/bodeweb.de\/blog\/siren-flotte-schiff-nr-5-geht-unter\/#primaryimage"},"thumbnailUrl":"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/08\/A1-Palau_652_389_90.jpg","datePublished":"2015-08-08T12:27:51+00:00","dateModified":"2020-09-04T19:21:21+00:00","description":"Mit der Palau Siren versinkt innerhalb weniger Jahre das f\u00fcnfte Schiff aus der Siren Flotte.","breadcrumb":{"@id":"https:\/\/bodeweb.de\/blog\/siren-flotte-schiff-nr-5-geht-unter\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bodeweb.de\/blog\/siren-flotte-schiff-nr-5-geht-unter\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bodeweb.de\/blog\/siren-flotte-schiff-nr-5-geht-unter\/#primaryimage","url":"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/08\/A1-Palau_652_389_90.jpg","contentUrl":"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/08\/A1-Palau_652_389_90.jpg","width":652,"height":389,"caption":"Palau Siren"},{"@type":"BreadcrumbList","@id":"https:\/\/bodeweb.de\/blog\/siren-flotte-schiff-nr-5-geht-unter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/bodeweb.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Siren Flotte: Schiff Nr. 5 l\u00e4uft auf Riff"}]},{"@type":"WebSite","@id":"https:\/\/bodeweb.de\/blog\/#website","url":"https:\/\/bodeweb.de\/blog\/","name":"BodeBlog-Tauchen in Indonesien","description":"Informationen \u00fcber Tauchen in Indonesien","publisher":{"@id":"https:\/\/bodeweb.de\/blog\/#\/schema\/person\/de787d16d54da0697c0bf296fbf34d03"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bodeweb.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/bodeweb.de\/blog\/#\/schema\/person\/de787d16d54da0697c0bf296fbf34d03","name":"Michael","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g","caption":"Michael"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g"}}]}},"_links":{"self":[{"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/posts\/2672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/comments?post=2672"}],"version-history":[{"count":0,"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/posts\/2672\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/media\/2676"}],"wp:attachment":[{"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/media?parent=2672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/categories?post=2672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/tags?post=2672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}