{"id":2790,"date":"2015-10-04T11:51:21","date_gmt":"2015-10-04T09:51:21","guid":{"rendered":"https:\/\/bodeweb.de\/blog\/?p=2790"},"modified":"2022-02-20T10:12:50","modified_gmt":"2022-02-20T09:12:50","slug":"neue-tauchbasen-tompotika-dive-lodge","status":"publish","type":"post","link":"https:\/\/bodeweb.de\/blog\/neue-tauchbasen-tompotika-dive-lodge\/","title":{"rendered":"Neue Tauchbasen: Tompotika Dive Lodge"},"content":{"rendered":"<p><a href=\"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/Tompotika-filled-w-roads2-e1442992425123.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-2793 size-medium\" src=\"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/Tompotika-filled-w-roads2-e1442992425123-300x200.jpg\" alt=\"Tompotika Dive Lodge Karte\" width=\"300\" height=\"200\" srcset=\"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/Tompotika-filled-w-roads2-e1442992425123-300x200.jpg 300w, https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/Tompotika-filled-w-roads2-e1442992425123-768x512.jpg 768w, https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/Tompotika-filled-w-roads2-e1442992425123.jpg 1000w, https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/Tompotika-filled-w-roads2-e1442992425123-300x200@2x.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>An der Ostspitze von Zentral-Sulawesi, <a href=\"https:\/\/bodeweb.de\/indonesien_tauchen.htm\">Indonesien<\/a>, etwa drei Stunden von <a href=\"https:\/\/bodeweb.de\/luwuk.htm\">Luwuk<\/a> entfernt auf der Balantak Halbinsel, liegt die neu er\u00f6ffnete <a href=\"http:\/\/www.divingsulawesi-tompotika.com\/\">Tompotika Dive Lodge<\/a>. Die Balantak\u00a0Halbinsel \u00f6stlich von Luwuk\u00a0liegt abseits der touristischen Pfade durch Sulawesi. Die Eigent\u00fcmer des neuen Resorts sind Yani Mile und Jerome Doucet. Beide wohnen in der N\u00e4he von Luwuk und betreiben von dort aus <a href=\"http:\/\/www.wallacea-divecruise.com\/\">Wallacea Dive Cruises<\/a> mit den beiden Tauchschiffen <a href=\"http:\/\/www.wallacea-divecruise.com\/boat\/ambai-liveaboard\">Ambai<\/a> und <a href=\"http:\/\/www.wallacea-divecruise.com\/boat\/calico-jack-liveaboard\">Calico Jack<\/a>.<\/p>\n<p>Nun kommt auch noch die Tompotika Dive Lodge dazu. Die Lodge besteht aus nur drei Bungalows, die alle mit Terrasse mit Meerblick und Bad\/WC ausgestattet sind. Elektrischer Strom steht 24h zur Verf\u00fcgung. Die Lodge liegt in unmittelbarer Nachbarschaft zu einem indonesischen Dorf, dessen Einwohner mit in das Projekt einbezogen wurden. Yani und Jerome haben das Ziel, die Gegend zu einem regionalen Naturschutzgebiet zu machen, in dem sowohl Meeres- als auch Landtiere gesch\u00fctzt werden. G\u00e4ste des Resorts zahlen daher auch einen geringen Naturschutzbeitrag, der dem Dorf und der Finanzierung von Schutzma\u00dfnahmen zugute kommen soll. Konkret geht es um den Schutz einer Kolonie der mittlerweile selten gewordenen Gro\u00dffu\u00dfh\u00fchner (Maleo) und um den Schutz von verschiedenen Str\u00e4nden, an denen Schildkr\u00f6ten ihre Eier ablegen.<\/p>\n<p>[gallery columns=&#8221;2&#8243; ids=&#8221;2800,2801,2798,2799&#8243;]<\/p>\n<h2>Tompotika Dive Lodge: Tauchen<\/h2>\n<div id=\"attachment_2797\" class=\"wp-caption alignleft\" style=\"width:300px;\"><a href=\"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/tompotika_uw.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2797 size-medium\" src=\"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/tompotika_uw-300x199.jpg\" alt=\"Tauchplatz Tompotika\" width=\"300\" height=\"199\" srcset=\"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/tompotika_uw-300x199.jpg 300w, https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/tompotika_uw-768x510.jpg 768w, https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/tompotika_uw.jpg 1024w, https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/tompotika_uw-300x199@2x.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p class=\"wp-caption-text\">Tompotika Dive Lodge Tauchplatz<\/p><\/div>\n<p>Tompotika ist taucherisches Neuland. Fr\u00fcher fuhr hier die Paisabatu auf dem Weg von Luwuk zu den Togian Inseln vorbei. Daher sind mir einige Tauchpl\u00e4tze bekannt. Es handelt sich vorwiegend um zerkl\u00fcftete Unterwasserberge und -k\u00e4mme, die mit Weichkorallen, schwarzen Korallen und Gorgonien bewachsen sind. An den Unterwasserbergen sammelt sich sehr viel Fisch. Mit Str\u00f6mung muss man hier immer rechnen. Die Lage am Rand des Indonesischen Durchflusses (Indonesian Throughflow) garantiert je nach Tageszeit und Mondphase zum Teil knackige Str\u00f6mungen. Daneben gibt es aber auch ruhige Buchten mit Sand- oder Ger\u00f6llfl\u00e4chen in denen man auf Critter-Jagd gehen kann. Direkt vor dem Resort kann man im schwarzen, vulkanischen Sand haarige Anglerfische, Blauringkraken und Geisterpfeifenfische finden. Also ein insgesamt abwechslungsreiches Angebot.<\/p>\n<p>Die beste Zeit zum Tauchen d\u00fcrfte zwischen Oktober und Mai sein. Bei einem Besuch im europ\u00e4ischen Sommer ist zwar auch Tauchen m\u00f6glich, allerdings werden viele exponierte Tauchpl\u00e4tze wegen der starken D\u00fcnung nicht zu erreichen sein.<\/p>\n<div id=\"attachment_2794\" class=\"wp-caption alignleft\" style=\"width:300px;\"><a href=\"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/maleo_sulawesi.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2794 size-medium\" src=\"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/maleo_sulawesi-300x136.jpg\" alt=\"Gr0\u00dffu\u00dfhuhn (Maleo)\" width=\"300\" height=\"136\" srcset=\"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/maleo_sulawesi-300x136.jpg 300w, https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/maleo_sulawesi-768x348.jpg 768w, https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/maleo_sulawesi.jpg 832w, https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/maleo_sulawesi-300x136@2x.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p class=\"wp-caption-text\">Gro\u00dffu\u00dfhuhn (Maleo)<\/p><\/div>\n<p>\u00dcber Wasser sind Ausfl\u00fcge zu den Maleo-Nistpl\u00e4tzen, zu Flughund-Kolonien auf den vorgelagerten Inseln und zu einer Lagune m\u00f6glich, wo man viele V\u00f6gel beobachten kann. Kayaks und Mountain Bikes k\u00f6nnen ausgeliehen werden. Sogar ein Katamaran steht f\u00fcr G\u00e4ste zur Verf\u00fcgung.<\/p>\n<h2><\/h2>\n<h2>Anreise<\/h2>\n<p>Luwuk ist mittlerweile besser erreichbar als fr\u00fcher. Es gibt dreimal w\u00f6chentlich Fl\u00fcge von Manado und zwei oder drei t\u00e4gliche Fl\u00fcge von Jakarta und Surabaya. Danach folgt der etwa dreist\u00fcndige Transfer mit dem Auto zur Tompotika Dive Lodge. Bei Buchung k\u00fcmmern sich Yani und Jerome auch um die Inlandsfl\u00fcge.<\/p>\n<p>Von Tompotika aus ist es auch m\u00f6glich, zu den <a href=\"https:\/\/bodeweb.de\/togians.htm\">Togian Inseln<\/a> weiter zu reisen. Bis nach Ampana dauert es mit dem Auto etwa sechs Stunden. Von Ampana fahren t\u00e4glich F\u00e4hren zu den Togian Inseln.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>An der Ostspitze von Zentral-Sulawesi, Indonesien, etwa drei Stunden von Luwuk entfernt auf der Balantak Halbinsel, liegt die neu er\u00f6ffnete Tompotika Dive Lodge. Die Balantak\u00a0Halbinsel \u00f6stlich von Luwuk\u00a0liegt abseits der&#8230;<span class=\"screen-reader-text\">  Neue Tauchbasen: Tompotika Dive Lodge<\/span><\/p>\n","protected":false},"author":1,"featured_media":2800,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[455],"tags":[13,17,19,30,53,65,108,123,138,196,201,342,381,382,385,433],"class_list":["post-2790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tauchen","tag-ambai","tag-ampana","tag-anglerfisch","tag-balantak","tag-blauringskrake","tag-calico-jack","tag-geisterpfeifenfisch","tag-grossfusshuhn","tag-indonesien","tag-luwuk","tag-maleo","tag-sulawesi","tag-togian","tag-togian-inseln","tag-tompotika-dive-lodge","tag-wallacea-dive-cruises"],"geo":{"latitude":-0.8569016,"longitude":123.3874512,"description":"Unnamed Road, Luok, Balantak, Kabupaten Banggai, Sulawesi Tengah, Indonesien"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neue Tauchbasen: Tompotika Dive Lodge - BodeBlog-Tauchen in Indonesien<\/title>\n<meta name=\"description\" content=\"Die Tompotika Dive Lodge ist eine neue Tauchbasis im Osten von Zentral-Sulawesi, Indonesien.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bodeweb.de\/blog\/neue-tauchbasen-tompotika-dive-lodge\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neue Tauchbasen: Tompotika Dive Lodge - BodeBlog-Tauchen in Indonesien\" \/>\n<meta property=\"og:description\" content=\"Die Tompotika Dive Lodge ist eine neue Tauchbasis im Osten von Zentral-Sulawesi, Indonesien.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bodeweb.de\/blog\/neue-tauchbasen-tompotika-dive-lodge\/\" \/>\n<meta property=\"og:site_name\" content=\"BodeBlog-Tauchen in Indonesien\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-04T09:51:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-20T09:12:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/tompotika_bungalow.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michael\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/neue-tauchbasen-tompotika-dive-lodge\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/neue-tauchbasen-tompotika-dive-lodge\\\/\"},\"author\":{\"name\":\"Michael\",\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/#\\\/schema\\\/person\\\/de787d16d54da0697c0bf296fbf34d03\"},\"headline\":\"Neue Tauchbasen: Tompotika Dive Lodge\",\"datePublished\":\"2015-10-04T09:51:21+00:00\",\"dateModified\":\"2022-02-20T09:12:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/neue-tauchbasen-tompotika-dive-lodge\\\/\"},\"wordCount\":542,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/#\\\/schema\\\/person\\\/de787d16d54da0697c0bf296fbf34d03\"},\"image\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/neue-tauchbasen-tompotika-dive-lodge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/tompotika_bungalow.jpg\",\"keywords\":[\"Ambai\",\"Ampana\",\"Anglerfisch\",\"Balantak\",\"Blauringskrake\",\"Calico Jack\",\"Geisterpfeifenfisch\",\"Gro\u00dffu\u00dfhuhn\",\"Indonesien\",\"Luwuk\",\"Maleo\",\"Sulawesi\",\"Togian\",\"Togian Inseln\",\"Tompotika Dive Lodge\",\"Wallacea Dive Cruises\"],\"articleSection\":[\"Tauchen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bodeweb.de\\\/blog\\\/neue-tauchbasen-tompotika-dive-lodge\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/neue-tauchbasen-tompotika-dive-lodge\\\/\",\"url\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/neue-tauchbasen-tompotika-dive-lodge\\\/\",\"name\":\"Neue Tauchbasen: Tompotika Dive Lodge - BodeBlog-Tauchen in Indonesien\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/neue-tauchbasen-tompotika-dive-lodge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/neue-tauchbasen-tompotika-dive-lodge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/tompotika_bungalow.jpg\",\"datePublished\":\"2015-10-04T09:51:21+00:00\",\"dateModified\":\"2022-02-20T09:12:50+00:00\",\"description\":\"Die Tompotika Dive Lodge ist eine neue Tauchbasis im Osten von Zentral-Sulawesi, Indonesien.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/neue-tauchbasen-tompotika-dive-lodge\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bodeweb.de\\\/blog\\\/neue-tauchbasen-tompotika-dive-lodge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/neue-tauchbasen-tompotika-dive-lodge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/tompotika_bungalow.jpg\",\"contentUrl\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/tompotika_bungalow.jpg\",\"width\":1500,\"height\":563,\"caption\":\"Tompotika Dive Lodge, Bungalow mit Meerblick\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/neue-tauchbasen-tompotika-dive-lodge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neue Tauchbasen: Tompotika Dive Lodge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/\",\"name\":\"BodeBlog-Tauchen in Indonesien\",\"description\":\"Informationen \u00fcber Tauchen in Indonesien\",\"publisher\":{\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/#\\\/schema\\\/person\\\/de787d16d54da0697c0bf296fbf34d03\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/bodeweb.de\\\/blog\\\/#\\\/schema\\\/person\\\/de787d16d54da0697c0bf296fbf34d03\",\"name\":\"Michael\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g\",\"caption\":\"Michael\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neue Tauchbasen: Tompotika Dive Lodge - BodeBlog-Tauchen in Indonesien","description":"Die Tompotika Dive Lodge ist eine neue Tauchbasis im Osten von Zentral-Sulawesi, Indonesien.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bodeweb.de\/blog\/neue-tauchbasen-tompotika-dive-lodge\/","og_locale":"de_DE","og_type":"article","og_title":"Neue Tauchbasen: Tompotika Dive Lodge - BodeBlog-Tauchen in Indonesien","og_description":"Die Tompotika Dive Lodge ist eine neue Tauchbasis im Osten von Zentral-Sulawesi, Indonesien.","og_url":"https:\/\/bodeweb.de\/blog\/neue-tauchbasen-tompotika-dive-lodge\/","og_site_name":"BodeBlog-Tauchen in Indonesien","article_published_time":"2015-10-04T09:51:21+00:00","article_modified_time":"2022-02-20T09:12:50+00:00","og_image":[{"width":1500,"height":563,"url":"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/tompotika_bungalow.jpg","type":"image\/jpeg"}],"author":"Michael","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Michael","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bodeweb.de\/blog\/neue-tauchbasen-tompotika-dive-lodge\/#article","isPartOf":{"@id":"https:\/\/bodeweb.de\/blog\/neue-tauchbasen-tompotika-dive-lodge\/"},"author":{"name":"Michael","@id":"https:\/\/bodeweb.de\/blog\/#\/schema\/person\/de787d16d54da0697c0bf296fbf34d03"},"headline":"Neue Tauchbasen: Tompotika Dive Lodge","datePublished":"2015-10-04T09:51:21+00:00","dateModified":"2022-02-20T09:12:50+00:00","mainEntityOfPage":{"@id":"https:\/\/bodeweb.de\/blog\/neue-tauchbasen-tompotika-dive-lodge\/"},"wordCount":542,"commentCount":0,"publisher":{"@id":"https:\/\/bodeweb.de\/blog\/#\/schema\/person\/de787d16d54da0697c0bf296fbf34d03"},"image":{"@id":"https:\/\/bodeweb.de\/blog\/neue-tauchbasen-tompotika-dive-lodge\/#primaryimage"},"thumbnailUrl":"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/tompotika_bungalow.jpg","keywords":["Ambai","Ampana","Anglerfisch","Balantak","Blauringskrake","Calico Jack","Geisterpfeifenfisch","Gro\u00dffu\u00dfhuhn","Indonesien","Luwuk","Maleo","Sulawesi","Togian","Togian Inseln","Tompotika Dive Lodge","Wallacea Dive Cruises"],"articleSection":["Tauchen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bodeweb.de\/blog\/neue-tauchbasen-tompotika-dive-lodge\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bodeweb.de\/blog\/neue-tauchbasen-tompotika-dive-lodge\/","url":"https:\/\/bodeweb.de\/blog\/neue-tauchbasen-tompotika-dive-lodge\/","name":"Neue Tauchbasen: Tompotika Dive Lodge - BodeBlog-Tauchen in Indonesien","isPartOf":{"@id":"https:\/\/bodeweb.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bodeweb.de\/blog\/neue-tauchbasen-tompotika-dive-lodge\/#primaryimage"},"image":{"@id":"https:\/\/bodeweb.de\/blog\/neue-tauchbasen-tompotika-dive-lodge\/#primaryimage"},"thumbnailUrl":"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/tompotika_bungalow.jpg","datePublished":"2015-10-04T09:51:21+00:00","dateModified":"2022-02-20T09:12:50+00:00","description":"Die Tompotika Dive Lodge ist eine neue Tauchbasis im Osten von Zentral-Sulawesi, Indonesien.","breadcrumb":{"@id":"https:\/\/bodeweb.de\/blog\/neue-tauchbasen-tompotika-dive-lodge\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bodeweb.de\/blog\/neue-tauchbasen-tompotika-dive-lodge\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bodeweb.de\/blog\/neue-tauchbasen-tompotika-dive-lodge\/#primaryimage","url":"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/tompotika_bungalow.jpg","contentUrl":"https:\/\/bodeweb.de\/blog\/wp-content\/uploads\/2015\/10\/tompotika_bungalow.jpg","width":1500,"height":563,"caption":"Tompotika Dive Lodge, Bungalow mit Meerblick"},{"@type":"BreadcrumbList","@id":"https:\/\/bodeweb.de\/blog\/neue-tauchbasen-tompotika-dive-lodge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/bodeweb.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Neue Tauchbasen: Tompotika Dive Lodge"}]},{"@type":"WebSite","@id":"https:\/\/bodeweb.de\/blog\/#website","url":"https:\/\/bodeweb.de\/blog\/","name":"BodeBlog-Tauchen in Indonesien","description":"Informationen \u00fcber Tauchen in Indonesien","publisher":{"@id":"https:\/\/bodeweb.de\/blog\/#\/schema\/person\/de787d16d54da0697c0bf296fbf34d03"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bodeweb.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/bodeweb.de\/blog\/#\/schema\/person\/de787d16d54da0697c0bf296fbf34d03","name":"Michael","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g","caption":"Michael"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/53b7ab5ea3943463de903d6b6915fadcc8c1d37027bf9624ab11bf2e707054f9?s=96&d=mm&r=g"}}]}},"_links":{"self":[{"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/posts\/2790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/comments?post=2790"}],"version-history":[{"count":0,"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/posts\/2790\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/media\/2800"}],"wp:attachment":[{"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/media?parent=2790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/categories?post=2790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bodeweb.de\/blog\/wp-json\/wp\/v2\/tags?post=2790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}